{"id":17,"count":2,"description":"","link":"https:\/\/blog.telecarerx.com\/index.php\/tag\/practice-management\/","name":"practice management","slug":"practice-management","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>practice management Archives - TeleCare Rx<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/blog.telecarerx.com\/index.php\/tag\/practice-management\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"practice management Archives - TeleCare Rx\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/blog.telecarerx.com\/index.php\/tag\/practice-management\/\" \/>\r\n<meta property=\"og:site_name\" content=\"TeleCare Rx\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.telecarerx.com\\\/index.php\\\/tag\\\/practice-management\\\/\",\"url\":\"https:\\\/\\\/blog.telecarerx.com\\\/index.php\\\/tag\\\/practice-management\\\/\",\"name\":\"practice management Archives - TeleCare Rx\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/telecarerxblog.azurewebsites.net\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.telecarerx.com\\\/index.php\\\/tag\\\/practice-management\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.telecarerx.com\\\/index.php\\\/tag\\\/practice-management\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/telecarerxblog.azurewebsites.net\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"practice management\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/telecarerxblog.azurewebsites.net\\\/#website\",\"url\":\"https:\\\/\\\/telecarerxblog.azurewebsites.net\\\/\",\"name\":\"TeleCare Rx\",\"description\":\"Patient Centered, Technology Driven\",\"publisher\":{\"@id\":\"https:\\\/\\\/telecarerxblog.azurewebsites.net\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/telecarerxblog.azurewebsites.net\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/telecarerxblog.azurewebsites.net\\\/#organization\",\"name\":\"TeleCare Rx\",\"url\":\"https:\\\/\\\/telecarerxblog.azurewebsites.net\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/telecarerxblog.azurewebsites.net\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/favicon2.png\",\"contentUrl\":\"\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/favicon2.png\",\"width\":256,\"height\":256,\"caption\":\"TeleCare Rx\"},\"image\":{\"@id\":\"https:\\\/\\\/telecarerxblog.azurewebsites.net\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"practice management Archives - TeleCare Rx","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.telecarerx.com\/index.php\/tag\/practice-management\/","og_locale":"en_US","og_type":"article","og_title":"practice management Archives - TeleCare Rx","og_url":"https:\/\/blog.telecarerx.com\/index.php\/tag\/practice-management\/","og_site_name":"TeleCare Rx","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.telecarerx.com\/index.php\/tag\/practice-management\/","url":"https:\/\/blog.telecarerx.com\/index.php\/tag\/practice-management\/","name":"practice management Archives - TeleCare Rx","isPartOf":{"@id":"https:\/\/telecarerxblog.azurewebsites.net\/#website"},"breadcrumb":{"@id":"https:\/\/blog.telecarerx.com\/index.php\/tag\/practice-management\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.telecarerx.com\/index.php\/tag\/practice-management\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/telecarerxblog.azurewebsites.net\/"},{"@type":"ListItem","position":2,"name":"practice management"}]},{"@type":"WebSite","@id":"https:\/\/telecarerxblog.azurewebsites.net\/#website","url":"https:\/\/telecarerxblog.azurewebsites.net\/","name":"TeleCare Rx","description":"Patient Centered, Technology Driven","publisher":{"@id":"https:\/\/telecarerxblog.azurewebsites.net\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/telecarerxblog.azurewebsites.net\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/telecarerxblog.azurewebsites.net\/#organization","name":"TeleCare Rx","url":"https:\/\/telecarerxblog.azurewebsites.net\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/telecarerxblog.azurewebsites.net\/#\/schema\/logo\/image\/","url":"\/wp-content\/uploads\/2021\/12\/favicon2.png","contentUrl":"\/wp-content\/uploads\/2021\/12\/favicon2.png","width":256,"height":256,"caption":"TeleCare Rx"},"image":{"@id":"https:\/\/telecarerxblog.azurewebsites.net\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/blog.telecarerx.com\/index.php\/wp-json\/wp\/v2\/tags\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.telecarerx.com\/index.php\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.telecarerx.com\/index.php\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.telecarerx.com\/index.php\/wp-json\/wp\/v2\/posts?tags=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}